{"id":2097,"date":"2021-04-21T15:03:44","date_gmt":"2021-04-21T13:03:44","guid":{"rendered":"https:\/\/www.mattheeuws.com\/medewerker\/celine-mattheeuws-copy-copy-copy\/"},"modified":"2022-02-03T08:24:32","modified_gmt":"2022-02-03T07:24:32","slug":"ojars-barkevics","status":"publish","type":"medewerker","link":"https:\/\/www.mattheeuws.com\/en\/medewerker\/ojars-barkevics\/","title":{"rendered":"Ojars Barkevics"},"content":{"rendered":"<p>Planning<\/p>\n<p><a href=\"mailto:o.barkevics@mattheeuws.com\"><img decoding=\"async\" class=\"alignnone\" src=\"https:\/\/www.mattheeuws.com\/wp-content\/uploads\/2020\/12\/medewerker_email.png\" alt=\"\" width=\"30\" height=\"30\" \/><\/a><\/p>\n","protected":false},"featured_media":3847,"template":"","categories":[38],"class_list":["post-2097","medewerker","type-medewerker","status-publish","has-post-thumbnail","hentry","category-planning-mattheeuws-en"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ojars Barkevics - Mattheeuws<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mattheeuws.com\/nl\/medewerker\/celine-mattheeuws-copy-copy-copy\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ojars Barkevics - Mattheeuws\" \/>\n<meta property=\"og:description\" content=\"Planning\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mattheeuws.com\/nl\/medewerker\/celine-mattheeuws-copy-copy-copy\/\" \/>\n<meta property=\"og:site_name\" content=\"Mattheeuws\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-03T07:24:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mattheeuws.com\/wp-content\/uploads\/2021\/04\/MATTHEEUWS_maart\u00a9HABLAR-44-scaled-e1724330584521.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1707\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.mattheeuws.com\/nl\/medewerker\/celine-mattheeuws-copy-copy-copy\/\",\"url\":\"https:\/\/www.mattheeuws.com\/nl\/medewerker\/celine-mattheeuws-copy-copy-copy\/\",\"name\":\"Ojars Barkevics - Mattheeuws\",\"isPartOf\":{\"@id\":\"https:\/\/www.mattheeuws.com\/nl\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.mattheeuws.com\/nl\/medewerker\/celine-mattheeuws-copy-copy-copy\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.mattheeuws.com\/nl\/medewerker\/celine-mattheeuws-copy-copy-copy\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.mattheeuws.com\/wp-content\/uploads\/2021\/04\/MATTHEEUWS_maart\u00a9HABLAR-44-scaled-e1724330584521.jpg\",\"datePublished\":\"2021-04-21T13:03:44+00:00\",\"dateModified\":\"2022-02-03T07:24:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.mattheeuws.com\/nl\/medewerker\/celine-mattheeuws-copy-copy-copy\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.mattheeuws.com\/nl\/medewerker\/celine-mattheeuws-copy-copy-copy\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.mattheeuws.com\/nl\/medewerker\/celine-mattheeuws-copy-copy-copy\/#primaryimage\",\"url\":\"https:\/\/www.mattheeuws.com\/wp-content\/uploads\/2021\/04\/MATTHEEUWS_maart\u00a9HABLAR-44-scaled-e1724330584521.jpg\",\"contentUrl\":\"https:\/\/www.mattheeuws.com\/wp-content\/uploads\/2021\/04\/MATTHEEUWS_maart\u00a9HABLAR-44-scaled-e1724330584521.jpg\",\"width\":1707,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.mattheeuws.com\/nl\/medewerker\/celine-mattheeuws-copy-copy-copy\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.mattheeuws.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ojars Barkevics\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.mattheeuws.com\/nl\/#website\",\"url\":\"https:\/\/www.mattheeuws.com\/nl\/\",\"name\":\"Mattheeuws\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.mattheeuws.com\/nl\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ojars Barkevics - Mattheeuws","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mattheeuws.com\/nl\/medewerker\/celine-mattheeuws-copy-copy-copy\/","og_locale":"en_US","og_type":"article","og_title":"Ojars Barkevics - Mattheeuws","og_description":"Planning","og_url":"https:\/\/www.mattheeuws.com\/nl\/medewerker\/celine-mattheeuws-copy-copy-copy\/","og_site_name":"Mattheeuws","article_modified_time":"2022-02-03T07:24:32+00:00","og_image":[{"width":1707,"height":2560,"url":"https:\/\/www.mattheeuws.com\/wp-content\/uploads\/2021\/04\/MATTHEEUWS_maart\u00a9HABLAR-44-scaled-e1724330584521.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.mattheeuws.com\/nl\/medewerker\/celine-mattheeuws-copy-copy-copy\/","url":"https:\/\/www.mattheeuws.com\/nl\/medewerker\/celine-mattheeuws-copy-copy-copy\/","name":"Ojars Barkevics - Mattheeuws","isPartOf":{"@id":"https:\/\/www.mattheeuws.com\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mattheeuws.com\/nl\/medewerker\/celine-mattheeuws-copy-copy-copy\/#primaryimage"},"image":{"@id":"https:\/\/www.mattheeuws.com\/nl\/medewerker\/celine-mattheeuws-copy-copy-copy\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mattheeuws.com\/wp-content\/uploads\/2021\/04\/MATTHEEUWS_maart\u00a9HABLAR-44-scaled-e1724330584521.jpg","datePublished":"2021-04-21T13:03:44+00:00","dateModified":"2022-02-03T07:24:32+00:00","breadcrumb":{"@id":"https:\/\/www.mattheeuws.com\/nl\/medewerker\/celine-mattheeuws-copy-copy-copy\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mattheeuws.com\/nl\/medewerker\/celine-mattheeuws-copy-copy-copy\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.mattheeuws.com\/nl\/medewerker\/celine-mattheeuws-copy-copy-copy\/#primaryimage","url":"https:\/\/www.mattheeuws.com\/wp-content\/uploads\/2021\/04\/MATTHEEUWS_maart\u00a9HABLAR-44-scaled-e1724330584521.jpg","contentUrl":"https:\/\/www.mattheeuws.com\/wp-content\/uploads\/2021\/04\/MATTHEEUWS_maart\u00a9HABLAR-44-scaled-e1724330584521.jpg","width":1707,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/www.mattheeuws.com\/nl\/medewerker\/celine-mattheeuws-copy-copy-copy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mattheeuws.com\/en\/"},{"@type":"ListItem","position":2,"name":"Ojars Barkevics"}]},{"@type":"WebSite","@id":"https:\/\/www.mattheeuws.com\/nl\/#website","url":"https:\/\/www.mattheeuws.com\/nl\/","name":"Mattheeuws","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mattheeuws.com\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.mattheeuws.com\/en\/wp-json\/wp\/v2\/medewerker\/2097","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mattheeuws.com\/en\/wp-json\/wp\/v2\/medewerker"}],"about":[{"href":"https:\/\/www.mattheeuws.com\/en\/wp-json\/wp\/v2\/types\/medewerker"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mattheeuws.com\/en\/wp-json\/wp\/v2\/media\/3847"}],"wp:attachment":[{"href":"https:\/\/www.mattheeuws.com\/en\/wp-json\/wp\/v2\/media?parent=2097"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mattheeuws.com\/en\/wp-json\/wp\/v2\/categories?post=2097"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}